{"id":116274,"date":"2019-07-06T13:51:13","date_gmt":"2019-07-06T18:51:13","guid":{"rendered":"http:\/\/laredsocial-noticias.com\/wp\/?p=116274"},"modified":"2019-07-06T13:51:25","modified_gmt":"2019-07-06T18:51:25","slug":"morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran","status":"publish","type":"post","link":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/","title":{"rendered":"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n"},"content":{"rendered":"<p>El Consejo Nacional de Morena no podr\u00e1 emitir la convocatoria para la renovaci\u00f3n de las dirigencias nacional, estatales, municipales y distritales, sin que previamente haya incluido a los cerca de los 10 millones de lopezobradoristas que tienen todo el derecho de tener su credencial actualizada de MORENA y dados de alta en el padr\u00f3n del INE, que es \u00fanica instituci\u00f3n que valida los padrones de los partidos pol\u00edticos para que se celebren elecciones internas en los mismos.<\/p>\n<p>Si no lo hacen y convocan sin haber cubierto este requisito legal y estatutario ante el INE y en los \u00f3rganos internos, estar\u00edan violando los derechos pol\u00edticos de millones de morenistas y tambi\u00e9n estar\u00edan cometiendo el delito de discriminaci\u00f3n y violencia pol\u00edtica en contra de quienes tambi\u00e9n tienen el leg\u00edtimo derecho de participar libre y democr\u00e1ticamente en las decisiones del movimiento.<\/p>\n<p>Pareciera que en Morena hay morenistas de primera, de segunda y de quinta, porque la Nomenclatura y los sectarios , antidemocr\u00e1ticos y facciosos, que se autodenominan &#8220;hist\u00f3ricos&#8221;, como si tuvieran un derecho superior a todos los dem\u00e1s.<\/p>\n<p>\u00c9se criterio tiene un f\u00e9tido olor supremacista, segregacionista y profundamente discriminatorio.<\/p>\n<p>No han le\u00eddo la Constituci\u00f3n pol\u00edtica de los Estados Unidos Mexicanos ni la Declaraci\u00f3n Universal de los Derechos del Hombre y del Ciudadano.<\/p>\n<p>\u00bfQu\u00e9 mayor violencia pol\u00edtica que erigirse en la casta superior por encima de todos los dem\u00e1s?<\/p>\n<p>Nuestros dirigentes en todo el pa\u00eds lo repiten como si fuesen una casta cuasi divina tocados por el dedo de la 4 Transformaci\u00f3n y s\u00f3lo ellos son poseedores de la verdad, del padr\u00f3n y de los procesos internos, dejando en la indefensi\u00f3n a los simples mortales de la base que, seg\u00fan ellos, no son dignos de la gracia de ingresar al reino de su cielo.<\/p>\n<p>Con esas \u00ednfulas, no s\u00f3lo ponen en riesgo el cambio de r\u00e9gimen, sino que le estamos abriendo la puerta a algo m\u00e1s grave: la discriminaci\u00f3n pol\u00edtica y la violaci\u00f3n de los derechos humanos de millones de lopezobradoristas.<\/p>\n<p>Estoy seguro que habr\u00e1 rebeli\u00f3n en las bases y no permitiremos que consumen ese atropello.<\/p>\n<p>La casta cuasi divina de los dizque &#8220;hist\u00f3ricos&#8221;, se pondr\u00e1n hist\u00e9ricos ante los verdaderos due\u00f1os de Morena: el pueblo de M\u00e9xico.<\/p>\n<p>Les vamos a ganar.<\/p>\n<p>Por una Morena democr\u00e1tica.<\/p>\n<p>\u00a1Juntos Haremos Morena!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Nacional de Morena no podr\u00e1 emitir la convocatoria para la renovaci\u00f3n de las dirigencias nacional, estatales, municipales y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[78,2801,6026,73],"tags":[7512,4959,183,611,1763,77],"class_list":["post-116274","post","type-post","status-publish","format-standard","hentry","category-nacional","category-politica","category-portada","category-principal","tag-alejandro-rojas-diaz-duran","tag-featured","tag-ine","tag-morena","tag-padron","tag-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n - NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n - NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"El Consejo Nacional de Morena no podr\u00e1 emitir la convocatoria para la renovaci\u00f3n de las dirigencias nacional, estatales, municipales y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIAS\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-06T18:51:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-06T18:51:25+00:00\" \/>\n<meta name=\"author\" content=\"Editor en Jefe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor en Jefe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n - NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/","og_locale":"es_ES","og_type":"article","og_title":"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n - NOTICIAS","og_description":"El Consejo Nacional de Morena no podr\u00e1 emitir la convocatoria para la renovaci\u00f3n de las dirigencias nacional, estatales, municipales y...","og_url":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/","og_site_name":"NOTICIAS","article_published_time":"2019-07-06T18:51:13+00:00","article_modified_time":"2019-07-06T18:51:25+00:00","author":"Editor en Jefe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor en Jefe","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/","url":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/","name":"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n - NOTICIAS","isPartOf":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#website"},"datePublished":"2019-07-06T18:51:13+00:00","dateModified":"2019-07-06T18:51:25+00:00","author":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0"},"breadcrumb":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laredsocial-noticias.com\/wp\/morena-no-podra-convocar-a-elecciones-sin-el-padron-actualizado-en-en-ine-alejandro-rojas-diaz-duran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laredsocial-noticias.com\/wp\/"},{"@type":"ListItem","position":2,"name":"MORENA no podr\u00e1 convocar a elecciones sin el padr\u00f3n actualizado en en INE: Alejandro Rojas D\u00edaz Dur\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/laredsocial-noticias.com\/wp\/#website","url":"https:\/\/laredsocial-noticias.com\/wp\/","name":"NOTICIAS","description":"Lo que se ve y se dice en las redes sociales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laredsocial-noticias.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0","name":"Editor en Jefe","url":"https:\/\/laredsocial-noticias.com\/wp\/author\/jorgeochoa\/"}]}},"_links":{"self":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/116274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/comments?post=116274"}],"version-history":[{"count":0,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/116274\/revisions"}],"wp:attachment":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/media?parent=116274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/categories?post=116274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/tags?post=116274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}