{"id":201650,"date":"2023-08-01T15:30:15","date_gmt":"2023-08-01T21:30:15","guid":{"rendered":"https:\/\/laredsocial-noticias.com\/wp\/?p=201650"},"modified":"2023-08-01T18:16:25","modified_gmt":"2023-08-02T00:16:25","slug":"detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm","status":"publish","type":"post","link":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/","title":{"rendered":"Detienen a pareja con 12 kilos de metanfetamina en el AICM"},"content":{"rendered":"<p>Un matrimonio de nacionalidad mexicana fue detenido en inmediaciones del Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) despu\u00e9s de que intentaran viajar con 12 kilos de metanfetamina.<\/p>\n<p>De acuerdo con los reportes, los detenidos transportaban la droga en maletas con doble fondo y pretend\u00edan llevarla a Narita, Jap\u00f3n, a trav\u00e9s de la aerol\u00ednea ANA.<\/p>\n<p>Los hechos ocurrieron la noche del lunes 31 de julio, cuando elementos de la Secretar\u00eda Marina identificaron mediante equipo de rayos X, maletas que conten\u00edan material org\u00e1nico.<\/p>\n<p>\u201cS<em>e avis\u00f3 a la responsable en turno de la aerol\u00ednea ANA para llevar a cabo el protocolo de inspecci\u00f3n establecido. En coordinaci\u00f3n con personal de seguridad del AICM y de la aerol\u00ednea, se identific\u00f3 a los propietarios del equipaje<\/em>\u201d, inform\u00f3.<\/p>\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\">\n<div class=\"wp-block-embed__wrapper\"><\/div>\n<\/figure>\n<p>Al inspeccionar el equipaje se constat\u00f3 que las maletas ten\u00edan doblo fondo que, al abrirlo, conten\u00edan paquetes con un polvo blanco cristalino granulado, que result\u00f3 ser metanfetamina.<\/p>\n<p>La pareja fue trasladada a oficinas de la Fiscal\u00eda General de la Rep\u00fablica (FGR) en el aeropuerto, donde ser\u00e1n puestos a disposici\u00f3n de la autoridad por posibles delitos contra la salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un matrimonio de nacionalidad mexicana fue detenido en inmediaciones del Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) despu\u00e9s de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91,6026],"tags":[261,1469,4959,77],"class_list":["post-201650","post","type-post","status-publish","format-standard","hentry","category-cdmx","category-portada","tag-cdmx","tag-ciudad-de-mexico","tag-featured","tag-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen a pareja con 12 kilos de metanfetamina en el AICM - NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen a pareja con 12 kilos de metanfetamina en el AICM - NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Un matrimonio de nacionalidad mexicana fue detenido en inmediaciones del Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) despu\u00e9s de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIAS\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-01T21:30:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T00:16:25+00:00\" \/>\n<meta name=\"author\" content=\"Editor en Jefe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor en Jefe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen a pareja con 12 kilos de metanfetamina en el AICM - NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen a pareja con 12 kilos de metanfetamina en el AICM - NOTICIAS","og_description":"Un matrimonio de nacionalidad mexicana fue detenido en inmediaciones del Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) despu\u00e9s de...","og_url":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/","og_site_name":"NOTICIAS","article_published_time":"2023-08-01T21:30:15+00:00","article_modified_time":"2023-08-02T00:16:25+00:00","author":"Editor en Jefe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor en Jefe","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/","url":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/","name":"Detienen a pareja con 12 kilos de metanfetamina en el AICM - NOTICIAS","isPartOf":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#website"},"datePublished":"2023-08-01T21:30:15+00:00","dateModified":"2023-08-02T00:16:25+00:00","author":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0"},"breadcrumb":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laredsocial-noticias.com\/wp\/detienen-a-pareja-con-12-kilos-de-metanfetamina-en-el-aicm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laredsocial-noticias.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Detienen a pareja con 12 kilos de metanfetamina en el AICM"}]},{"@type":"WebSite","@id":"https:\/\/laredsocial-noticias.com\/wp\/#website","url":"https:\/\/laredsocial-noticias.com\/wp\/","name":"NOTICIAS","description":"Lo que se ve y se dice en las redes sociales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laredsocial-noticias.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0","name":"Editor en Jefe","url":"https:\/\/laredsocial-noticias.com\/wp\/author\/jorgeochoa\/"}]}},"_links":{"self":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/201650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/comments?post=201650"}],"version-history":[{"count":1,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/201650\/revisions"}],"predecessor-version":[{"id":201651,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/201650\/revisions\/201651"}],"wp:attachment":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/media?parent=201650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/categories?post=201650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/tags?post=201650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}