{"id":26056,"date":"2016-09-01T17:38:34","date_gmt":"2016-09-01T22:38:34","guid":{"rendered":"http:\/\/laredsocial-noticias.com\/wp\/?p=26056"},"modified":"2016-09-01T17:40:31","modified_gmt":"2016-09-01T22:40:31","slug":"ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional","status":"publish","type":"post","link":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/","title":{"rendered":"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26057 alignleft\" src=\"http:\/\/laredsocial-noticias.com\/wp\/wp-content\/uploads\/2016\/09\/ensayo_ute_lemper_RMM_1137b.jpg\" alt=\"ensayo_ute_lemper_RMM_1137b\" width=\"391\" height=\"277\" data-wp-pid=\"26057\" \/><\/p>\n<p>Por Jos\u00e9 Garc\u00eda Segura<\/p>\n<p>La cantante alemana Ute Lemper (M\u00fcnster, Alemania, 1963), despu\u00e9s de dos a\u00f1os de ausencia en los escenarios mexicanos, ofrecer\u00e1 dos conciertos en la Sala Principal del Palacio de Bellas Artes, acompa\u00f1ada de la Orquesta Sinf\u00f3nica Nacional, con la direcci\u00f3n de Carlos Miguel Prieto.<\/p>\n<p>La reconocida artista cantar\u00e1 en la primera parte del concierto, acompa\u00f1ada del cuarteto vocal estadounidense Hudson Shad, Los siete pecados capitales, en la que colaboraron por \u00faltima vez Bertolt Brecht y Kurt Weill. Para la segunda parte interpretar\u00e1 canciones de compositores pertenecientes a diferentes \u00e9pocas: John Kander, Jacques Brel y un medley de George Gershwin.<\/p>\n<p>En conferencia de prensa, la protagonista de la comedia Peter Pan en Berl\u00edn, Alemania (1995), dijo estar feliz de regresar a M\u00e9xico e indic\u00f3 que Los siete pecados capitales es una de sus obras favoritas, la cual interpretar\u00e1 en el d\u00e9cimo concierto de la temporada 2016 de la OSN.<\/p>\n<p>&nbsp;<\/p>\n<h1><strong>Carlos Maceiras ofreci\u00f3 recital con m\u00fasica de Heitor Villa-Lobos y temas de\u00a0<em>bossa nova<\/em><\/strong><\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26058\" src=\"http:\/\/laredsocial-noticias.com\/wp\/wp-content\/uploads\/2016\/09\/carlos_maceiras_RMM_1081b.jpg\" alt=\"carlos_maceiras_RMM_1081b\" width=\"332\" height=\"235\" data-wp-pid=\"26058\" \/><\/p>\n<p>Carlos Maceiras, guitarrista, compositor y arreglista, transport\u00f3 al p\u00fablico, a trav\u00e9s de sus cuerdas, a las playas y los parajes de Brasil en el octavo concierto del proyecto A\u00f1o de Allegro y Andante, con composiciones del brasile\u00f1o Heitor Villa-Lobos (1881-1959) y temas de bossa nova.<\/p>\n<p>En el Foro Cultural Coyoacanense Hugo Arg\u00fcelles el p\u00fablico disfrut\u00f3 de la ejecuci\u00f3n de cada una de las 11 piezas que interpret\u00f3 el m\u00fasico acompa\u00f1ado por un par de guitarras, las cuales intercambiaba entre pieza y pieza.<\/p>\n<p>Preludio 1, 2, 3, 4 y Vals-choro, de Villa- Lobos; Bossa; Berimbao-consolaci\u00f3n y El astronauta, de Powell; Meditaci\u00f3n y Samba de una sola nota, de Antonio Carlos Jobim, junto con Dos cantos a Villa-Lobos, compuesta por el mexicano Juan Helguera, fueron temas que disfrutaron los asistentes por m\u00e1s de una hora.<\/p>\n<p>Nacido en la Ciudad de M\u00e9xico, Maceiras cuenta con una amplia trayectoria dentro de la m\u00fasica, tanto a nivel nacional como en el extranjero, condecorado en 1988 por el gobierno de Brasil con la Medalla Villa-Lobos, por difusi\u00f3n e interpretaci\u00f3n del compositor y su concepto respecto a la m\u00fasica popular de las culturas.<\/p>\n<p>El recital es parte de A\u00f1o de Allegro y Andante, serie de 12 presentaciones durante este 2016, con el objetivo de interpretar 84 obras diferentes del mundo entero para guitarra de concierto, como muestra de la interrelaci\u00f3n de las artes y las posibilidades de un instrumento tan com\u00fan e importante para tantas culturas: la guitarra.<\/p>\n<p>Heitor Villa-Lobos (II), R\u00edo de Janeiro, Brasil. 1881- 1959, t\u00edtulo de la presentaci\u00f3n musical con la cual plasm\u00f3 la diversidad, calidad y frescura que existe en los ritmos cariocas, al pasar de la melancol\u00eda al carnaval a partir de los acordes.<\/p>\n<p>Preludio 1, de Heitor Villa-Lobos dio inicio al concierto con tonos graves acompa\u00f1ados por una magnifica melod\u00eda, m\u00e1s tarde la bossa nova brind\u00f3 una atm\u00f3sfera relajada en la que Maceiras manifest\u00f3 su alegr\u00eda con cada una de las ejecuciones en el escenario.<\/p>\n<p>Tras disfrutar del excelente recital, j\u00f3venes y adultos reconocieron con sus aplausos el trabajo del guitarrista, quien se entreg\u00f3 en cada minuto a la interpretaci\u00f3n de la m\u00fasica al lado de su instrumento.<\/p>\n<p>La pr\u00f3xima fecha de A\u00f1o de Allegro y Andante ser\u00e1 el mi\u00e9rcoles 8 de septiembre con el programa que lleva el t\u00edtulo Latinoam\u00e9rica II, en el Foro Cultural Coyoacanense Hugo Arg\u00fcelles ubicado en Ignacio Allende No. 36, Colonia Del Carmen, en Coyoac\u00e1n, Ciudad de M\u00e9xico. Entrada libre.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"57WctaMip5\"><p><a href=\"https:\/\/laredsocial-noticias.com\/wp\/la-ultima-entrevista-de-juan-gabriel-sin-hueso-ni-cenizas\/\">La \u00faltima entrevista de Juan Gabriel, sin hueso ni cenizas<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLa \u00faltima entrevista de Juan Gabriel, sin hueso ni cenizas\u00bb \u2014 NOTICIAS\" src=\"https:\/\/laredsocial-noticias.com\/wp\/la-ultima-entrevista-de-juan-gabriel-sin-hueso-ni-cenizas\/embed\/#?secret=dZ6j4y8eIu#?secret=57WctaMip5\" data-secret=\"57WctaMip5\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Jos\u00e9 Garc\u00eda Segura La cantante alemana Ute Lemper (M\u00fcnster, Alemania, 1963), despu\u00e9s de dos a\u00f1os de ausencia en los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[946],"tags":[],"class_list":["post-26056","post","type-post","status-publish","format-standard","hentry","category-cultura-y-entretenimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill - NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill - NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Por Jos\u00e9 Garc\u00eda Segura La cantante alemana Ute Lemper (M\u00fcnster, Alemania, 1963), despu\u00e9s de dos a\u00f1os de ausencia en los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIAS\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-01T22:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-01T22:40:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laredsocial-noticias.com\/wp\/wp-content\/uploads\/2016\/09\/carlos_maceiras_RMM_1081b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor en Jefe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor en Jefe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill - NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill - NOTICIAS","og_description":"Por Jos\u00e9 Garc\u00eda Segura La cantante alemana Ute Lemper (M\u00fcnster, Alemania, 1963), despu\u00e9s de dos a\u00f1os de ausencia en los...","og_url":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/","og_site_name":"NOTICIAS","article_published_time":"2016-09-01T22:38:34+00:00","article_modified_time":"2016-09-01T22:40:31+00:00","og_image":[{"width":1417,"height":1004,"url":"https:\/\/laredsocial-noticias.com\/wp\/wp-content\/uploads\/2016\/09\/carlos_maceiras_RMM_1081b.jpg","type":"image\/jpeg"}],"author":"Editor en Jefe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor en Jefe","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/","url":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/","name":"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill - NOTICIAS","isPartOf":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/#primaryimage"},"image":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/#primaryimage"},"thumbnailUrl":"http:\/\/laredsocial-noticias.com\/wp\/wp-content\/uploads\/2016\/09\/ensayo_ute_lemper_RMM_1137b.jpg","datePublished":"2016-09-01T22:38:34+00:00","dateModified":"2016-09-01T22:40:31+00:00","author":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0"},"breadcrumb":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/laredsocial-noticias.com\/wp\/ute-lemper-interpretara-los-siete-pecados-capitales-de-kurt-weill-acompanada-de-la-sinfonica-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laredsocial-noticias.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Ute Lemper interpretar\u00e1\u00a0Los siete pecados capitales,\u00a0de Kurt Weill"}]},{"@type":"WebSite","@id":"https:\/\/laredsocial-noticias.com\/wp\/#website","url":"https:\/\/laredsocial-noticias.com\/wp\/","name":"NOTICIAS","description":"Lo que se ve y se dice en las redes sociales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laredsocial-noticias.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0","name":"Editor en Jefe","url":"https:\/\/laredsocial-noticias.com\/wp\/author\/jorgeochoa\/"}]}},"_links":{"self":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/26056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/comments?post=26056"}],"version-history":[{"count":2,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/26056\/revisions"}],"predecessor-version":[{"id":26060,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/26056\/revisions\/26060"}],"wp:attachment":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/media?parent=26056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/categories?post=26056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/tags?post=26056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}