{"id":61582,"date":"2017-04-23T13:50:54","date_gmt":"2017-04-23T18:50:54","guid":{"rendered":"http:\/\/laredsocial-noticias.com\/wp\/?p=61582"},"modified":"2017-04-23T13:55:19","modified_gmt":"2017-04-23T18:55:19","slug":"ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero","status":"publish","type":"post","link":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/","title":{"rendered":"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero"},"content":{"rendered":"<p>LA RED SOCIAL. Ciudad de M\u00e9xico 23 de abril.- La ley para la creaci\u00f3n de una Fiscal\u00eda Anticorrupci\u00f3n est\u00e1 ya turnada a las comisiones, es una ley bien construida y podr\u00eda discutirse ya en los pr\u00f3ximos d\u00edas, advirti\u00f3 el Presidente del Senado de la Rep\u00fablica, Pablo Escudero.<\/p>\n<p>Dijo estar sorprendido por los comentarios de algunos legisladores de diversos partidos por la \u201cmala fe\u201d o la \u201cignorancia\u201d que muestran al hablar del tema, pues existe un acuerdo promulgado por la PGR, que fue aprobada en el Senado.<\/p>\n<p>Ese acuerdo para la creaci\u00f3n de la Fiscal\u00eda Anticorrupci\u00f3n se hizo en el 2014, todav\u00eda con Jes\u00fas Murillo Karam como procurador. En el 2016 se hicieron modificaciones a diversas leyes para homologarlas para crear ese nuevo \u00f3rgano. La PGR acaba de publicar el decreto en el Diario Oficial.<\/p>\n<p>Derivado de esa homologaci\u00f3n, sali\u00f3 ese decreto publicado en el DOF. \u201cCualquiera que hubiera estado en el Senado, porque yo me imagino que no son comentarios de Senadores, hubiera recordado lo que votamos\u201d.<\/p>\n<p>\u201cSi ustedes agarran la Ley Org\u00e1nica de lo que votamos de la Procuradur\u00eda y lo comparan con el Acuerdo, se dar\u00e1n cuenta de que es pr\u00e1cticamente lo mismo\u201d, sentenci\u00f3 tajante el l\u00edder del Senado de la Rep\u00fablica.<\/p>\n<p>Lo que se est\u00e1 haciendo es homologar el marco normativo. Lo que hay que hacer es sentarnos ya a construir la modificaci\u00f3n a la ley\u00a0 de la propia Fiscal\u00eda General, lo que vamos a hacer con el fiscal anticorrupci\u00f3n y cu\u00e1ndo vamos a activar los mecanismos para el nombramiento del Fiscal General.<\/p>\n<p>Estas tres cosas s\u00ed ameritar\u00edan tener un Periodo Extraordinario para atender: 1.- la parte normativa 2.-La parte del Fiscal Anticorrupci\u00f3n y 3.- la parte del nombramiento del Fiscal General.<\/p>\n<p>Escobar plante\u00f3 incluso que \u00e9ste \u00faltimo punto se realice ante el Pleno del Senado, para que ah\u00ed comparezcan los nominados ante los 128 legisladores.<\/p>\n<p>El Presidente de la Mesa Directiva del Senado de la Rep\u00fablica, insisti\u00f3 por tanto que quienes critican el Acuerdo A\/029\/17 emitido por la Procuradur\u00eda General de la Rep\u00fablica respecto a las atribuciones de la Fiscali\u0301a Especializada en materia de Delitos relacionados con Hechos de Corrupcio\u0301n, lo hacen por ignorancia o por mala fe.<\/p>\n<p>La PGR simplemente armoniz\u00f3 un acuerdo que hab\u00eda sido publicado el 12 de marzo de 2014 en el Diario Oficial de la Federacio\u0301n, es decir, antes de la expedici\u00f3n, en 2016, de las leyes secundarias en materia de combate a la corrupci\u00f3n, con el objeto de determinar puntualmente la participacio\u0301n de la Fiscal\u00eda dentro del Sistema Nacional Anticorrpuci\u00f3n<\/p>\n<p>El Acuerdo emitido esta semana por la PGR, tan s\u00f3lo homologa el Acuerdo A\/011\/14, en el que se describ\u00edan las atribuciones de la recien creada Fiscali\u0301a Anticorrupci\u00f3n, con el Decreto por el que se reformo\u0301 la Ley Orga\u0301nica de la Procuraduri\u0301a General de la Repu\u0301blica, que fue expedido dos a\u00f1os m\u00e1s tarde, dentro del paquete de leyes secundarias anticorrupci\u00f3n.<\/p>\n<p>El presidente de la C\u00e1mara alta invit\u00f3 a los detractores de la Procuradur\u00eda General, a leer el apartado de Considerandos del Acuerdo y conocer los antecedentes de las reformas en materia de combate a la corrupci\u00f3n que han sido discutidas y aprobadas por el Congreso de la Uni\u00f3n en los \u00faltimos a\u00f1os.<\/p>\n<p>Record\u00f3 que legisladores de todos los partidos, votamos y aprobamos estas reformas, por lo que tan s\u00f3lo se trata de armonizar las atribuciones de la Fiscal\u00eda respecto a los servicios periciales, al nombramiento de los ministerios p\u00fablicos, su participaci\u00f3n como integrante del Sistema Nacional Anticorrupci\u00f3n, entre otros.<\/p>\n<p>Finalmente, el presidente del Senado sentenci\u00f3 que aquellos que declaran de mala fe son casos perdidos que habremos de evidenciar en todo momento para evitar que sigan enga\u00f1ando; sin embargo, los que declaran por ignorancia est\u00e1n a tiempo de leer y ponerse a estudiar.<\/p>\n<p>&nbsp;<\/p>\n<table width=\"604\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"299\"><strong>L<\/strong><strong>EY\u00a0<\/strong><strong>O<\/strong><strong>RGA\u0301NICA DE LA\u00a0<\/strong><strong>P<\/strong><strong>ROCURADURI\u0301A\u00a0<\/strong><strong>G<\/strong><strong>ENERAL DE LA<\/strong><strong>R<\/strong><strong>EPU\u0301BLICA<\/strong><strong>.<\/strong><\/td>\n<td colspan=\"2\" width=\"304\"><strong>ACUERDO<\/strong><strong>\u00a0<\/strong><strong>A\/029\/17<\/strong><strong>\u00a0POR EL QUE SE MODIFICA EL DIVERSO\u00a0<\/strong><strong>A\/011\/14\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\">Arti\u0301culo 10 Bis, p\u00e1rrafo tercero<\/td>\n<td width=\"214\">La Fiscali\u0301a Especializada para el desarrollo de sus funciones se auxiliara\u0301 de la unidad administrativa\u00a0<strong><u>en materia deServicios Periciales, la cual en<\/u>\u00a0<u>su caso, debera\u0301 dar tra\u0301mite ydesahogo al peritaje solicitado<\/u>\u00a0<u>en el te\u0301rmino que al efecto<\/u>\u00a0<u>establezca el Ministerio<\/u>\u00a0<u>Pu\u0301blico y que resulte acorde<\/u>\u00a0<u>con la complejidad del peritaje<\/u>\u00a0<u>a realizar<\/u><\/strong>.<\/td>\n<td width=\"85\">Art\u00edculo<\/p>\n<p>SEGUNDO,<\/p>\n<p>p\u00e1rrafo quinto<\/td>\n<td width=\"219\">La Fiscali\u0301a Especializada en materia de Delitos relacionados con Hechos de Corrupcio\u0301n para el desarrollo de sus funciones\u00a0<strong><u>se<\/u>\u00a0<u>auxiliara\u0301 de la Coordinacio\u0301n<\/u>\u00a0<u>General de Servicios Periciales,<\/u>\u00a0<u>quien desahogara\u0301 los peritajes<\/u>\u00a0<u>que le soliciten los agentes de<\/u><\/strong><\/p>\n<p><strong><u>Ministerio \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pu\u0301blico \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 de \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 la<\/u><\/strong><\/p>\n<p><strong><u>Federacio\u0301n adscritos a e\u0301sta<\/u><\/strong>.<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">Arti\u0301culo 10 Bis, p\u00e1rrafo segundo<\/td>\n<td width=\"214\">Contara\u0301 con el personal sustantivo, directivo, administrativo y auxiliar capacitados para el debido cumplimiento de sus funciones, asi\u0301 como con las unidades administrativas necesarias para el seguimiento de las investigaciones.<\/td>\n<td width=\"85\">Art\u00edculo<\/p>\n<p>SEGUNDO,<\/p>\n<p>p\u00e1rrafo tercero<\/td>\n<td width=\"219\">Asimismo, contara\u0301 con el personal sustantivo especializado, directivo, administrativo y auxiliar capacitado para el debido cumplimiento de sus funciones.<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">Arti\u0301culo 10 Bis, p\u00e1rrafo quinto<\/td>\n<td width=\"214\">Su titular\u00a0<strong><u>presentara\u0301<\/u>\u00a0<u>anualmente al Procurador<\/u>\u00a0<u>General de la Repu\u0301blica un<\/u>\u00a0<u>informe sobre actividades<\/u>\u00a0<u>sustantivas y sus resultados<\/u><\/strong>, el cual sera\u0301 pu\u0301blico, en te\u0301rminos de lo previsto en la Ley General de Transparencia y Acceso a la Informacio\u0301n Pu\u0301blica, y dema\u0301s disposiciones aplicables en la materia. Dicho informe sera\u0301 remitido a su vez, al Comite\u0301<\/p>\n<p>Coordinador del Sistema Nacional Anticorrupcio\u0301n y al Senado de la Repu\u0301blica.<\/td>\n<td width=\"85\">Art\u00edculo<\/p>\n<p>TERCERO<\/td>\n<td width=\"219\">El Fiscal\u00a0<strong><u>presentara\u0301 anualmente<\/u>\u00a0<u>al Procurador General de la<\/u>\u00a0<u>Repu\u0301blica un informe sobre<\/u>\u00a0<u>actividades sustantivas y sus<\/u>\u00a0<u>resultados<\/u><\/strong>, el cual sera\u0301 pu\u0301blico, en te\u0301rminos de lo previsto en la Ley General de Transparencia y Acceso a la Informacio\u0301n Pu\u0301blica, la Ley Federal de Transparencia y Acceso a la Informacio\u0301n Pu\u0301blica, y dema\u0301s disposiciones aplicables en la materia. Dicho informe sera\u0301 remitido a su vez, al Comite\u0301 Coordinador del Sistema Nacional Anticorrupcio\u0301n y al Senado de la Repu\u0301blica<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">Arti\u0301culo 10 Bis, p\u00e1rrafo sexto<\/td>\n<td width=\"214\">El titular de la Fiscali\u0301a, al igual que su personal de confianza, agentes del Ministerio Pu\u0301blico de la Federacio\u0301n, agentes de la Polici\u0301a Federal Ministerial y peritos miembros del Servicio Profesional de Carrera o de designacio\u0301n especial estara\u0301n sujetos a la Ley General de Responsabilidades<\/p>\n<p>Administrativas, asi\u0301 como al re\u0301gimen especial de la materia<\/td>\n<td width=\"85\">Art\u00edculo<\/p>\n<p>TERCERO<\/p>\n<p>BIS<\/td>\n<td width=\"219\">El Titular de la Fiscali\u0301a Especializada en Materia de Delitos relacionados con Hechos de Corrupcio\u0301n, al igual que su personal de confianza, agentes del Ministerio Pu\u0301blico de la Federacio\u0301n, agentes de la Polici\u0301a Federal Ministerial y peritos estara\u0301n sujetos a la Ley General de Responsabilidades<\/p>\n<p>Administrativas, asi\u0301 como al re\u0301gimen especial de la materia<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><\/td>\n<td width=\"214\">previsto en esta ley. Su actuacio\u0301n sera\u0301 fiscalizada por la Auditori\u0301a Superior de la Federacio\u0301n, la Visitaduri\u0301a General y el O\u0301rgano Interno de Control, conforme a sus respectivas competencias.<\/td>\n<td width=\"85\"><\/td>\n<td width=\"219\">previsto en la Ley Orga\u0301nica de la Procuraduri\u0301a General de la<\/p>\n<p>Repu\u0301blica.<\/p>\n<p>Su actuacio\u0301n sera\u0301 fiscalizada por la Auditori\u0301a Superior de la<\/p>\n<p>Federacio\u0301n, la Visitaduri\u0301a General y el O\u0301rgano Interno de Control, conforme a sus respectivas competencias.<\/td>\n<\/tr>\n<tr>\n<td width=\"85\">Arti\u0301culo 10 Ter, p\u00e1rrafo primero<\/td>\n<td width=\"214\">La Fiscali\u0301a Especializada en materia de delitos relacionados con hechos de corrupcio\u0301n contara\u0301 con las siguientes atribuciones:<\/td>\n<td width=\"85\">Art\u00edculo<\/p>\n<p>CUARTO,<\/p>\n<p>p\u00e1rrafo primero<\/td>\n<td width=\"219\">El Titular de la Fiscali\u0301a Especializada en Materia de Delitos relacionados con Hechos de Corrupcio\u0301n contara\u0301 con las facultades siguientes:<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><iframe loading=\"lazy\" title=\"FISCAL ANTICORRUPCION\" width=\"740\" height=\"555\" src=\"https:\/\/www.youtube.com\/embed\/r_XoV-XVylc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA RED SOCIAL. Ciudad de M\u00e9xico 23 de abril.- La ley para la creaci\u00f3n de una Fiscal\u00eda Anticorrupci\u00f3n est\u00e1 ya&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,59,10],"tags":[2819,3611],"class_list":["post-61582","post","type-post","status-publish","format-standard","hentry","category-congreso-de-la-union","category-senado","category-transparencia-y-corrupcion","tag-fiscalia-anticorrupcion","tag-pablo-escudero-morales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero - NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero - NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"LA RED SOCIAL. Ciudad de M\u00e9xico 23 de abril.- La ley para la creaci\u00f3n de una Fiscal\u00eda Anticorrupci\u00f3n est\u00e1 ya...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIAS\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-23T18:50:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-23T18:55:19+00:00\" \/>\n<meta name=\"author\" content=\"Editor en Jefe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor en Jefe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero - NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/","og_locale":"es_ES","og_type":"article","og_title":"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero - NOTICIAS","og_description":"LA RED SOCIAL. Ciudad de M\u00e9xico 23 de abril.- La ley para la creaci\u00f3n de una Fiscal\u00eda Anticorrupci\u00f3n est\u00e1 ya...","og_url":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/","og_site_name":"NOTICIAS","article_published_time":"2017-04-23T18:50:54+00:00","article_modified_time":"2017-04-23T18:55:19+00:00","author":"Editor en Jefe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor en Jefe","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/","url":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/","name":"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero - NOTICIAS","isPartOf":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#website"},"datePublished":"2017-04-23T18:50:54+00:00","dateModified":"2017-04-23T18:55:19+00:00","author":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0"},"breadcrumb":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laredsocial-noticias.com\/wp\/ignorancia-o-mala-fe-los-que-critican-acuerdo-de-la-pgr-sobre-fiscalia-anticorrupcion-escudero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laredsocial-noticias.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Ignorancia o mala fe, los que critican acuerdo de la PGR sobre Fiscal\u00eda Anticorrupci\u00f3n: Escudero"}]},{"@type":"WebSite","@id":"https:\/\/laredsocial-noticias.com\/wp\/#website","url":"https:\/\/laredsocial-noticias.com\/wp\/","name":"NOTICIAS","description":"Lo que se ve y se dice en las redes sociales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laredsocial-noticias.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/0ce78643f2de7aae6f6ef10e8453a6e0","name":"Editor en Jefe","url":"https:\/\/laredsocial-noticias.com\/wp\/author\/jorgeochoa\/"}]}},"_links":{"self":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/61582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/comments?post=61582"}],"version-history":[{"count":0,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/61582\/revisions"}],"wp:attachment":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/media?parent=61582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/categories?post=61582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/tags?post=61582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}