{"id":82077,"date":"2017-11-09T16:15:47","date_gmt":"2017-11-09T21:15:47","guid":{"rendered":"http:\/\/laredsocial-noticias.com\/wp\/?p=82077"},"modified":"2017-11-09T16:15:47","modified_gmt":"2017-11-09T21:15:47","slug":"pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion","status":"publish","type":"post","link":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/","title":{"rendered":"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n"},"content":{"rendered":"<p>Por cuarto a\u00f1o consecutivo, la Ley de Ingresos prev\u00e9 la asignaci\u00f3n de un monto equivalente a la recaudaci\u00f3n estimada a partir del impuesto a las bebidas azucaradas para destinarse a programas de promoci\u00f3n, prevenci\u00f3n, detecci\u00f3n, tratamiento, control y combate (\u2026) al sobrepeso, obesidad y enfermedades cr\u00f3nico degenerativas relativas, as\u00ed como para apoyar acciones de acceso al agua potable para beber en las escuelas.<\/p>\n<p>Sin embargo, esto no se ha visto reflejado en el presupuesto de acuerdo a un an\u00e1lisis elaborado por la consultora Probatio para la Alianza por la Salud Alimentaria.<\/p>\n<p>En noviembre 2016 la propia Secretar\u00eda de Salud declar\u00f3 emergencias epidemiol\u00f3gicas por obesidad y por diabetes, resaltando que es la primera ocasi\u00f3n en que un pa\u00eds declara una emergencia de este tipo por enfermedades no transmisibles, debido a la magnitud del problema. Tras la declaraci\u00f3n se esperaba el anuncio de una serie de medidas para enfrentar estas declaratorias, sin embargo, nunca fueron presentadas.<\/p>\n<p>Para la Organizaci\u00f3n Mundial de la Salud y otros organismos internacionales como la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico, la prevenci\u00f3n es la estrategia de largo plazo m\u00e1s eficaz para revertir el grave problema de sobrepeso y obesidad en el mundo, lo que en M\u00e9xico deber\u00eda traducirse no en acciones aisladas, sino en una verdadera pol\u00edtica de Estado.<\/p>\n<p>Esta pol\u00edtica de prevenci\u00f3n debe contar con una visi\u00f3n estrat\u00e9gica y de largo plazo que utilice instrumentos legales, institucionales y presupuestarios para hacer frente de forma efectiva y transparente a la epidemia, m\u00e1s all\u00e1 de una Estrategia con caducidad sexenal e intervenida por intereses privados.<\/p>\n<p>De acuerdo a Atzimba Baltazar, consultora de Probatio, \u201cel gravamen a las bebidas azucaradas y los alimentos con alta densidad cal\u00f3rica constituye una ventana de oportunidad, la cual ha sido desaprovechada por el actual gobierno\u201d.<\/p>\n<p>El an\u00e1lisis muestra que existe un importante desbalance entre los recursos recaudados por el IEPS a alimentos con alta densidad cal\u00f3rica y bebidas azucaradas, y el presupuesto que se destina a programas con componentes de prevenci\u00f3n del sobrepeso y la obesidad o para garantizar el acceso al agua potable.<\/p>\n<p>Para el 2018 la diferencia entre estos dos montos es de 29,710 millones de pesos, resultado de la diferencia de la recaudaci\u00f3n estimada en 46,726 millones y el presupuesto asignado a estos programas de 17,016 millones. De este \u00faltimo monto hay que recordar que tan solo 1,189 millones est\u00e1 destinado a los bebederos y el suministro continuo de agua potable en las escuelas.<\/p>\n<p>El IEPS es un impuesto denominado \u201cextrafiscal\u201d, que debe funcionar como instrumento de pol\u00edtica p\u00fablica, dise\u00f1ado para corregir externalidades que el consumo de ciertos productos provoca en la poblaci\u00f3n, a diferencia de un impuesto \u201cfiscal\u201d, cuyo objetivo es recaudar contribuciones para sufragar el gasto p\u00fablico gubernamental en general.<\/p>\n<p>El estudio presentado narra algunas experiencias internacionales, que ejemplifican la forma en que un impuesto \u201cextrafiscal\u201d se devuelve a la sociedad en forma de bienes y servicios que buscan transformar un ambiente obesog\u00e9nico en uno saludable.<\/p>\n<p>Federico Cort\u00e9s, consultor de Probatio declar\u00f3 \u201ccomo ejemplos de programas operados con recursos derivados de la recaudaci\u00f3n est\u00e1n: el de acceso a agua potable, a alimentos saludables, educaci\u00f3n nutricional y alimentaria, activaci\u00f3n f\u00edsica, entre otros programas de salud, con \u00e9nfasis en grupos vulnerables, as\u00ed como inversiones no solo en escuelas, parques y espacios recreativos sino tambi\u00e9n en bibliotecas como ocurrir\u00e1 en Filadelfia, Estados Unidos. A lo anterior se le ha denominado una normativa de segunda generaci\u00f3n, que busca otorgar bienestar a la poblaci\u00f3n permitiendo ahorros en gastos m\u00e9dicos, mejoras en su salud y por ende en su calidad de vida\u201d.<\/p>\n<p>Por su parte Fiorella Espinosa, investigadora en salud alimentaria en El Poder del Consumidor dijo \u201cen M\u00e9xico el \u00fanico avance al respecto que surgi\u00f3 a ra\u00edz del impuesto es la implementaci\u00f3n del Programa Nacional de Bebederos, sin embargo, tiene como limitante la ausencia de un mecanismo de transparencia y rendici\u00f3n de cuentas en tiempo real\u201d.<\/p>\n<p>Una de las fortalezas de las experiencias compartidas es precisamente la existencia de mecanismos de transparencia, rendici\u00f3n de cuentas y participaci\u00f3n en el ciclo de la pol\u00edtica del impuesto, lo que permite monitorear y evaluar el uso de los recursos. Destaca adem\u00e1s la creaci\u00f3n de cuerpos colegiados, multidisciplinarios y libres de conflicto de inter\u00e9s que definen el uso de los recursos con base en las necesidades, adem\u00e1s de dar seguimiento cercano a la pol\u00edtica.<\/p>\n<p>Finalmente, el estudio incluye tres recomendaciones puntuales que se pueden realizar de manera inmediata y que pueden ser un punto de partida para transitar hacia esquemas de \u201csegunda generaci\u00f3n\u201d:<\/p>\n<p>1) Aumentar a 20% el IEPS a bebidas azucaradas y equiparar el \u201cpiso m\u00ednimo\u201d de gasto p\u00fablico para programas de prevenci\u00f3n con el monto recaudado;<\/p>\n<p>2) Hacer transparentes y monitorear los recursos destinados a la prevenci\u00f3n del sobrepeso, la obesidad y asegurar el acceso al agua potable para dise\u00f1ar acciones que realmente provean bienes y servicios efectivos y<\/p>\n<p>3) Hacer transparente el avance de los recursos destinados a la instalaci\u00f3n y mantenimiento de bebederos en centros escolares.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por cuarto a\u00f1o consecutivo, la Ley de Ingresos prev\u00e9 la asignaci\u00f3n de un monto equivalente a la recaudaci\u00f3n estimada a&#8230;<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[389,73,2849],"tags":[949,5403],"class_list":["post-82077","post","type-post","status-publish","format-standard","hentry","category-mexico","category-principal","category-salud","tag-diabetes","tag-emergencia-epidemiologica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n - NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n - NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Por cuarto a\u00f1o consecutivo, la Ley de Ingresos prev\u00e9 la asignaci\u00f3n de un monto equivalente a la recaudaci\u00f3n estimada a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/\" \/>\n<meta property=\"og:site_name\" content=\"NOTICIAS\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-09T21:15:47+00:00\" \/>\n<meta name=\"author\" content=\"Juan Raymundo Hernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Raymundo Hernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n - NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/","og_locale":"es_ES","og_type":"article","og_title":"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n - NOTICIAS","og_description":"Por cuarto a\u00f1o consecutivo, la Ley de Ingresos prev\u00e9 la asignaci\u00f3n de un monto equivalente a la recaudaci\u00f3n estimada a...","og_url":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/","og_site_name":"NOTICIAS","article_published_time":"2017-11-09T21:15:47+00:00","author":"Juan Raymundo Hernandez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Raymundo Hernandez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/","url":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/","name":"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n - NOTICIAS","isPartOf":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#website"},"datePublished":"2017-11-09T21:15:47+00:00","author":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/ef87465aef7eca376539490cfb6ab6dc"},"breadcrumb":{"@id":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/laredsocial-noticias.com\/wp\/pese-a-la-emergencia-epidemiologica-por-obesidad-y-diabetes-no-existe-una-politica-presupuestaria-integral-de-prevencion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laredsocial-noticias.com\/wp\/"},{"@type":"ListItem","position":2,"name":"Pese a la emergencia epidemiol\u00f3gica por obesidad y diabetes, no existe una pol\u00edtica presupuestaria integral de prevenci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/laredsocial-noticias.com\/wp\/#website","url":"https:\/\/laredsocial-noticias.com\/wp\/","name":"NOTICIAS","description":"Lo que se ve y se dice en las redes sociales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laredsocial-noticias.com\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/laredsocial-noticias.com\/wp\/#\/schema\/person\/ef87465aef7eca376539490cfb6ab6dc","name":"Juan Raymundo Hernandez","url":"https:\/\/laredsocial-noticias.com\/wp\/author\/juanraymundohernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/82077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/comments?post=82077"}],"version-history":[{"count":0,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/posts\/82077\/revisions"}],"wp:attachment":[{"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/media?parent=82077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/categories?post=82077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laredsocial-noticias.com\/wp\/wp-json\/wp\/v2\/tags?post=82077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}